{"id":3769,"date":"2021-11-12T13:24:01","date_gmt":"2021-11-12T13:24:01","guid":{"rendered":"https:\/\/www.bertschi-cafe.ch\/webseite\/kaffeebohne-kaufen-hilfreiche-tipps-zur-auswahl-des-richtigen-kaffees\/"},"modified":"2024-03-16T22:27:43","modified_gmt":"2024-03-16T22:27:43","slug":"kaffeebohne-kaufen-hilfreiche-tipps-zur-auswahl-des-richtigen-kaffees","status":"publish","type":"post","link":"https:\/\/www.bertschi-cafe.ch\/it\/kaffeebohne-kaufen-hilfreiche-tipps-zur-auswahl-des-richtigen-kaffees\/","title":{"rendered":"Kaffeebohne kaufen: Hilfreiche Tipps zur Auswahl des richtigen Kaffees"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Kaffee geh\u00f6rt in vielen L\u00e4ndern zu den beliebtesten Getr\u00e4nken. In der Schweiz etwa trinkt jeder B\u00fcrger <\/span><a href=\"https:\/\/www.srf.ch\/news\/schweiz\/kaffeeland-schweiz-taeglich-fast-drei-tassen-und-am-liebsten-einen-cafe-creme\"><span style=\"font-weight: 400;\">durchschnittlich fast drei Tassen Kaffee am Tag<\/span><\/a><span style=\"font-weight: 400;\">. Damit liegen wir Schweizer hinter den Norwegern und den Deutschen auf dem dritten Platz der Kaffee-Weltrangliste. Doch um das Heissgetr\u00e4nk wirklich geniessen zu k\u00f6nnen, sollte man hochwertige <a href=\"https:\/\/www.bertschi-cafe.ch\/produkt\/basler-cafe\/\">Kaffeebohnen<\/a> kaufen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Im Folgenden erl\u00e4utern wir Ihnen, was gute Kaffeebohnen ausmacht und worauf Sie beim Kauf unbedingt achten sollten. Zudem verraten wir Ihnen, welche Kaffeemischungen und anderen Produkte Sie im <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/shop\/\"><span style=\"font-weight: 400;\">Online-Shop von Bertschi-Caf\u00e9<\/span><\/a><span style=\"font-weight: 400;\"> erhalten.\u00a0<\/span><\/p>\n<h2><b>Worauf muss ich achten, wenn ich Kaffeebohnen kaufen will?\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Einen ersten Anhaltspunkt, ob eine Kaffeemischung gut oder schlecht ist, liefert bereits die Verpackung. Man muss also nicht unbedingt die Kaffeebohnen sehen, um minderwertige Produkte ausschliessen zu k\u00f6nnen. Wichtig ist etwa, dass die Verpackung ein Aroma-Ventil aufweist. Es hat zwei Funktionen: Es l\u00e4sst CO2 aus der Packung und verhindert, dass Sauerstoff eindringt.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Es ist normal, dass Kaffeebohnen nach dem R\u00f6sten und Verpacken CO2 abgeben. W\u00fcrde es an der Verpackung kein Ventil geben, dann w\u00fcrde das CO2 das Aroma belasten. Dass die verpackten Kaffeebohnen nicht mit Sauerstoff in Kontakt kommen, sorgt f\u00fcr eine l\u00e4ngere Haltbarkeit.\u00a0<\/span><\/p>\n<h2><b>Zertifizierungen sprechen f\u00fcr hohe Qualit\u00e4t\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">Ein Zeichen daf\u00fcr, dass Sie hochwertige Kaffeebohnen kaufen, sind Siegel auf der Verpackung. Sie k\u00f6nnen zeigen,\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">dass der Produzent auf einen biologischen und nachhaltigen Anbau der Kaffeebohnen setzt.\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">dass der Produzent die Kaffeebauern fair f\u00fcr ihre Leistungen verg\u00fctet.\u00a0<\/span><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Biologischer Anbau mit Blick auf Nachhaltigkeit bringt qualit\u00e4tvolle Bohnen hervor \u2013 ebenso wie motivierte Kaffeebauern. Werden sie fair bezahlt, dann arbeiten sie sorgf\u00e4ltiger.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Wir von Bertschi-Caf\u00e9 legen sowohl <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/unser-kaffee\/\"><span style=\"font-weight: 400;\">auf Bio-Qualit\u00e4t als auch auf Fair-Trade<\/span><\/a><span style=\"font-weight: 400;\"> grossen Wert. Daher sind wir von folgenden Organisationen zertifiziert:\u00a0<\/span><\/p>\n<ul>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bertschi-cafe.ch\/unser-kaffee\/bio-suisse\/\"><span style=\"font-weight: 400;\">Bio Suisse<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bertschi-cafe.ch\/unser-kaffee\/euro-bio\/\"><span style=\"font-weight: 400;\">EURO-Bio<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bertschi-cafe.ch\/unser-kaffee\/max-havelaar\/\"><span style=\"font-weight: 400;\">Max Havelaar-Stiftung<\/span><\/a><span style=\"font-weight: 400;\">\u00a0<\/span><\/li>\n<li style=\"font-weight: 400;\" aria-level=\"1\"><a href=\"https:\/\/www.bertschi-cafe.ch\/webseite\/demeter-zertifizierung\/\"><span style=\"font-weight: 400;\">Demeter\u00a0<\/span><\/a><\/li>\n<\/ul>\n<p><span style=\"font-weight: 400;\">Wenn Sie also bei uns Kaffeebohnen kaufen, dann k\u00f6nnen Sie sich auf Bio-Anbau und eine faire Verg\u00fctung der Kaffeebauern verlassen.\u00a0<\/span><\/p>\n<h2><b>Wie sehen hochwertige Kaffeebohnen aus?<\/b><\/h2>\n<p><img decoding=\"async\" class=\"aligncenter wp-image-16783 size-full\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffeebohnen.jpg\" alt=\"Kaffeebohnen\" width=\"800\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Gute Kaffeebohnen erkennen Sie daran, dass sie etwa gleich gross sind und eine weitgehend glatte Oberfl\u00e4che haben. Die Einheitlichkeit in der Gr\u00f6sse ist durch die Art der R\u00f6stung begr\u00fcndet. Dabei unterscheidet man zwischen der Trommel- und der industriellen R\u00f6stung.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">F\u00fcr die schnelle Massenproduktion von Kaffeebohnen kommt die industrielle R\u00f6stung zum Einsatz. Dabei werden die Bohnen f\u00fcr kurze Zeit besonders heisser Luft ausgesetzt. Um Zeit zu sparen, werden die Bohnen zudem vorher nicht sortiert. Daher ist es nicht un\u00fcblich, dass kleinere Exemplare beim R\u00f6sten verbrennen. Gr\u00f6ssere Bohnen sind hingegen aufgrund des schnellen Vorgehens oftmals innen noch roh.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Dies geht selbstverst\u00e4ndlich zulasten des Aromas. Da vor der industriellen R\u00f6stung \u00fcblicherweise keine Sortierung stattfindet, werden auch keine Fremdk\u00f6rper entfernt. In der fertigen Mischung k\u00f6nnen also Astst\u00fccke oder Steinchen enthalten sein. Auch diese sind f\u00fcr den fertigen Kaffee nicht gerade verteilhaft.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ganz anders sieht es bei der Trommelr\u00f6stung aus, die auch wir von Bertschi-Caf\u00e9 f\u00fcr die Herstellung unserer Kaffeemischungen einsetzen. Zun\u00e4chst werden die Kaffeebohnen nach Gr\u00f6sse sortiert und eventuelle Fremdk\u00f6rper entfernt. Dann wird eine relativ kleine Menge an Bohnen in die Trommel gegeben. Der R\u00f6stmeister erhitzt diese auf etwa 200 Grad Celsius und dreht sie 14 bis 24 Minuten lang.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Die Dauer der <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/unser-kaffee\/roestung\/\"><span style=\"font-weight: 400;\">R\u00f6stung<\/span><\/a><span style=\"font-weight: 400;\"> ist wesentlich f\u00fcr das Aroma der Kaffeemischung. Der R\u00f6stmeister weiss genau, wie lange er die Bohnen in der Trommel lassen muss, um ein zufriedenstellendes Ergebnis zu erreichen. Nach dem R\u00f6sten k\u00fchlen die Bohnen an der Luft ab. Wollen Sie hochwertige Kaffeebohnen kaufen, dann sollten Sie also zu einer Mischung greifen, die per Trommelr\u00f6stung entstanden ist.\u00a0<\/span><\/p>\n<h2><b>Keine Flecken, Risse und Bissl\u00f6cher<\/b><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-15878 aligncenter\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/nur-wenige-gebrochene-bohnen.jpg\" alt=\"Kaffeebohnen\" width=\"800\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Die Optik der Kaffeebohnen l\u00e4sst ebenfalls deutliche R\u00fcckschl\u00fcsse auf ihre Qualit\u00e4t zu. So sollten sie nur wenige bis gar keine L\u00f6cher aufweisen. Diese sprechen n\u00e4mlich daf\u00fcr, dass die Kaffeekirschen von Sch\u00e4dlingen befallen worden sind. Ein geh\u00e4uftes Auftreten von Bissl\u00f6chern spricht daf\u00fcr, dass die Kirschen nicht sortiert worden sind.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Auch dunkle Flecken an den Bohnen sind ein Zeichen f\u00fcr minderwertige Qualit\u00e4t. Denn sie entstehen, wenn schimmelige Bohnen ger\u00f6stet wurden. Schimmel kann sich an den Kaffeekirschen bilden, wenn sie nach der Ernte nicht gleichm\u00e4ssig getrocknet wurden.\u00a0\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">\u00dcber eine Gef\u00e4hrdung der Gesundheit muss man sich keine Sorgen machen, wenn man solche Bohnen f\u00fcr seinen Kaffee verwendet. Schliesslich werden Bakterien und andere Krankheitserreger bei den hohen Temperaturen abget\u00f6tet, die beim R\u00f6sten erreicht werden. Allerdings spricht es eine deutliche Sprache, wenn der Produzent verschimmelte Kaffeebohnen weiterverarbeitet.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Risse in den Kaffeebohnen k\u00f6nnen ebenfalls ein Merkmal f\u00fcr schlechte Qualit\u00e4t sein. Es k\u00f6nnte aber auch sein, dass der R\u00f6stmeister den Bohnen \u00fcberdurchschnittlich viel Feuchtigkeit entzieht. Dies kann ebenfalls Risse hervorrufen, die dann aber nicht f\u00fcr schlechte Bohnen sprechen. Daher sind Risse nicht immer ein Zeichen f\u00fcr minderwertige Kaffeebohnen.\u00a0<\/span><\/p>\n<h2><b>Wo kann ich Kaffeebohnen kaufen?\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">In jedem Supermarkt gibt es g\u00fcnstige Kaffeemischungen. Der relativ niedrige Preis veranlasst viele Kunden dazu, die Kaffeebohnen zu kaufen. Wir raten Ihnen jedoch davon ab. Denn es ist damit zu rechnen, dass die Bohnen industriell ger\u00f6stet wurden. Nur so kann der Anbieter den niedrigen Preis rechtfertigen. Doch wie bereits ausgef\u00fchrt, geht die industrielle R\u00f6stung zu Lasten der Qualit\u00e4t.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Sollten Sie gute Kaffeebohnen kaufen wollen, lohnt es sich daher, dies bei einem Anbieter zu tun, der die Trommelr\u00f6stung nutzt. Wir von Bertschi-Caf\u00e9 greifen aus \u00dcberzeugung von jeher auf diese Methode zur\u00fcck. Daher k\u00f6nnen Sie bei uns stets beste Qualit\u00e4t erwarten.\u00a0<\/span><\/p>\n<h2><b>Das abwechslungsreiche Sortiment von Bertschi-Caf\u00e9<\/b><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-16784 aligncenter\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/bertschi-cafe.jpg\" alt=\"bertschi caf\u00e9\" width=\"800\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">In unserem <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/shop\/\"><span style=\"font-weight: 400;\">Online-Shop<\/span><\/a><span style=\"font-weight: 400;\"> finden Sie zahlreiche Kaffeemischungen, die ganz bestimmt Ihren Geschmack treffen werden. Um sie ganz einfach zu finden, haben wir praktische Filterm\u00f6glichkeiten integriert. Damit k\u00f6nnen Sie sich beispielsweise nur helle, mittlere oder dunkle R\u00f6stungen anzeigen lassen.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Auch eine Sortierung nach der Eignung f\u00fcr eine bestimmte Kaffeezubereitung ist m\u00f6glich. So finden Sie etwa Mischungen, die Sie bevorzugt f\u00fcr Caf\u00e9 Crema oder f\u00fcr Espresso verwenden k\u00f6nnen. \u00dcber die Filter sind auch <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/shop\/filter\/pa_zubereitung-filter:126\/\"><span style=\"font-weight: 400;\">koffeinfreie Mischungen<\/span><\/a><span style=\"font-weight: 400;\"> und unser <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/shop\/filter\/pa_zubereitung-filter:125\/\"><span style=\"font-weight: 400;\">Instant-Kaffee<\/span><\/a><span style=\"font-weight: 400;\"> leicht aufzufinden.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein Highlight in unserem Shop ist auch der regelm\u00e4ssig wechselnde <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/produkt\/saison-kaffee\/\"><span style=\"font-weight: 400;\">Saison-Kaffee<\/span><\/a><span style=\"font-weight: 400;\">. Noch f\u00fcr kurze Zeit handelt es sich dabei derzeit um eine Herbst-Mischung aus Arabica- und Robusta-Bohnen. Sie ist geradezu pr\u00e4destiniert daf\u00fcr, dass Sie sie an k\u00fchlen Herbsttagen geniessen.\u00a0<\/span><\/p>\n<h2><b>Geschenk-Ideen von Bertschi-Caf\u00e9 <\/b><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-16785 aligncenter\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/geschenk-ideen-von-bertschi-cafe.jpg\" alt=\"Geschenk-Ideen von Bertschi-Caf\u00e9 \" width=\"800\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Nicht nur in der Vorweihnachtszeit sind Geschenk-Ideen h\u00f6chst willkommen. Wir von Bertschi-Caf\u00e9 haben diesbez\u00fcglich einiges im Angebot. Wie w\u00e4re es etwa mit einem unserer <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/shop\/filter\/product_cat:116\/\"><span style=\"font-weight: 400;\">Kaffee-Sets<\/span><\/a><span style=\"font-weight: 400;\">? Darin sind nicht nur verschiedene Kaffeemischungen in unterschiedlichen R\u00f6stgraden enthalten. Es geh\u00f6ren auch zwei Tassen mit Tellern dazu. So kann die beschenkte Person gleich die Mischungen probieren.\u00a0<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Ein wundervolles Geschenk stellen auch unsere <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/produkt\/geschenk-gutschein\/\"><span style=\"font-weight: 400;\">Gutscheine<\/span><\/a><span style=\"font-weight: 400;\"> dar. Diese k\u00f6nnen Sie im Wert von 20, 50 oder 100 CHF bei uns erwerben. Sie berechtigen die beschenkte Person dazu, in diesem Wert die Produkte aus unserem Shop auszuw\u00e4hlen, die ihr zusagen.\u00a0\u00a0<\/span><\/p>\n<h2><b>Individuelle R\u00f6stungen\u00a0<\/b><\/h2>\n<p><span style=\"font-weight: 400;\">\u00dcbrigens bieten wir auch die M\u00f6glichkeit, individuelle R\u00f6stungen bei uns zu erwerben. Dieses Angebot machen wir Privatpersonen bei einer Abnahme ab zehn Kilogramm Kaffeebohnen. Als Firmenkunde m\u00fcssen mindestens 40 Kilogramm bestellen, damit wir die R\u00f6stungen nach Ihren Vorstellungen vornehmen.\u00a0<\/span><\/p>\n<h2><b>Ihr Kontakt zu Bertschi-Caf\u00e9<\/b><\/h2>\n<p><img decoding=\"async\" class=\"size-full wp-image-16786 aligncenter\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffeebohne-kaufen.jpg\" alt=\"Kaffeebohne kaufen\" width=\"800\" height=\"500\" \/><\/p>\n<p><span style=\"font-weight: 400;\">Sollten Sie Fragen zu unserem Sortiment oder unseren Dienstleistungen haben, dann wenden Sie sich sehr gerne an uns. Nutzen Sie daf\u00fcr das <\/span><a href=\"https:\/\/www.bertschi-cafe.ch\/webseite\/kontakt\/\"><span style=\"font-weight: 400;\">Kontaktformular auf unserer Webseite<\/span><\/a><span style=\"font-weight: 400;\">. Dort finden Sie auch unsere Telefonnummer und unsere E-Mail-Adresse. Z\u00f6gern Sie nicht, uns zu schreiben oder anzurufen. Wir freuen uns auf Ihre Kontaktaufnahme.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Kaffee geh\u00f6rt in vielen L\u00e4ndern zu den beliebtesten Getr\u00e4nken. In der Schweiz etwa trinkt jeder B\u00fcrger durchschnittlich fast drei Tassen Kaffee am Tag. Damit liegen wir Schweizer hinter den Norwegern und den Deutschen auf dem dritten Platz der Kaffee-Weltrangliste. Doch um das Heissgetr\u00e4nk wirklich geniessen zu k\u00f6nnen, sollte man hochwertige Kaffeebohnen kaufen.\u00a0 Im Folgenden erl\u00e4utern [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":3774,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[303,305,306,110],"tags":[],"class_list":["post-3769","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bester-kaffee","category-kaffee-kaufen","category-kaffeebohnen","category-tipps"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/posts\/3769","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/comments?post=3769"}],"version-history":[{"count":1,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/posts\/3769\/revisions"}],"predecessor-version":[{"id":24752,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/posts\/3769\/revisions\/24752"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/media\/3774"}],"wp:attachment":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/media?parent=3769"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/categories?post=3769"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/tags?post=3769"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}