{"id":31438,"date":"2024-11-01T13:50:14","date_gmt":"2024-11-01T13:50:14","guid":{"rendered":"https:\/\/www.bertschi-cafe.ch\/?page_id=31438"},"modified":"2024-11-26T17:03:09","modified_gmt":"2024-11-26T17:03:09","slug":"geschenksets","status":"publish","type":"page","link":"https:\/\/www.bertschi-cafe.ch\/it\/geschenksets\/","title":{"rendered":"Geschenksets"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"31438\" class=\"elementor elementor-31438\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d4297c0 e-flex e-con-boxed e-con e-parent\" data-id=\"d4297c0\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-b3521d8 e-con-full e-flex e-con e-child\" data-id=\"b3521d8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t<div class=\"elementor-element elementor-element-2dd85d9 e-con-full e-flex e-con e-child\" data-id=\"2dd85d9\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4300c5b elementor-widget elementor-widget-heading\" data-id=\"4300c5b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Verschenken Sie echten Kaffeegenuss<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6618f61 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6618f61\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"#Bertschi-Versprechen\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Das Bertschi-Versprechen<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5f9ed94 elementor-widget elementor-widget-image\" data-id=\"5f9ed94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke.webp\" class=\"attachment-full size-full wp-image-31626\" alt=\"\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke.webp 1024w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-300x300.webp 300w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-150x150.webp 150w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-768x768.webp 768w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-700x700.webp 700w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-600x600.webp 600w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/kaffee-geschenke-100x100.webp 100w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-982a1b8 e-flex e-con-boxed e-con e-parent\" data-id=\"982a1b8\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-459a305 elementor-widget elementor-widget-heading\" data-id=\"459a305\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Exklusive Kaffee-Sets f\u00fcr jeden Anlass<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-34442c9 elementor-widget elementor-widget-text-editor\" data-id=\"34442c9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecken Sie die Welt exquisiter Kaffees mit unseren massgeschneiderten Geschenksets<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa63044 elementor-widget elementor-widget-spacer\" data-id=\"aa63044\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-71365c4 elementor-product-loop-item--align-center elementor-grid-mobile-1 elementor-grid-4 elementor-grid-tablet-3 elementor-products-grid elementor-wc-products elementor-widget elementor-widget-woocommerce-products\" data-id=\"71365c4\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"woocommerce-products.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"woocommerce columns-4 \"><ul class=\"products elementor-grid columns-4\">\n<li class=\"product type-product post-20713 status-publish first instock product_cat-geschenk-und-probiersets has-post-thumbnail sale taxable shipping-taxable purchasable product-type-simple\">\n\t<a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-da-caffe-equo-e-solidale\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"cg-badge-container\"><div class=\"cg-badge\"><img decoding=\"async\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/02\/bertschi-cafe-labels-logo-fairtrade-max-havelaar-1.svg\" alt=\"Caff\u00e8 equo e solidale\" title=\"Caff\u00e8 equo e solidale\"><\/div><\/div><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-2-bertschi-cafe-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Set da caff\u00e8 equo e solidale\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-2-bertschi-cafe-300x300.jpg 300w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-2-bertschi-cafe-150x150.jpg 150w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-2-bertschi-cafe-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Set da caff\u00e8 equo e solidale<\/h2>\n\t<span class=\"price\"><ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;67.45<\/bdi><\/span><\/ins> <del><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;75.40<\/bdi><\/span><\/del><\/span>\n<\/a><div class=\"custom-group\"><span class=\"price\"><ins><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;67.45<\/bdi><\/span><\/ins> <del><span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;75.40<\/bdi><\/span><\/del><\/span><div class=\"woocommerce-loop-product__buttons\"><a href=\"\/it\/wp-json\/wp\/v2\/pages\/31438?add-to-cart=20713\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_20713\" data-quantity=\"1\" class=\"button product_type_simple add_to_cart_button ajax_add_to_cart\" data-product_id=\"20713\" data-product_sku=\"8417b4b7a649\" aria-label=\"Aggiungi al carrello: &quot;Set da caff\u00e8 equo e solidale&quot;\" rel=\"nofollow\" data-success_message=\"&quot;Set da caff\u00e8 equo e solidale&quot; \u00e8 stato aggiunto al tuo carrello\" role=\"button\">Aggiungi al carrello<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20713\" class=\"screen-reader-text\">\n\t\t\t<\/span>\n<\/div><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:20713,&quot;item_id&quot;:20713,&quot;item_name&quot;:&quot;Set da caff\\u00e8 equo e solidale&quot;,&quot;sku&quot;:&quot;8417b4b7a649&quot;,&quot;price&quot;:67.4500000000000028421709430404007434844970703125,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Set regalo e degustazione&quot;,&quot;id&quot;:20713,&quot;productlink&quot;:&quot;https:\\\/\\\/www.bertschi-cafe.ch\\\/it\\\/prodotto\\\/set-da-caffe-equo-e-solidale\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:1,&quot;product_type&quot;:&quot;simple&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span>\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"20713\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[20713] = {\"id\":\"20713\",\"sku\":\"8417b4b7a649\",\"price\":69.2000000000000028421709430404007434844970703125,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"20713\",\"sku\":\"8417b4b7a649\",\"gpf\":\"woocommerce_gpf_20713\",\"gla\":\"gla_20713\"},\"is_variable\":false,\"type\":\"simple\",\"name\":\"Set da caff\u00e8 equo e solidale\",\"category\":[\"Set regalo e degustazione\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[20713]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t<\/li>\n<li class=\"product type-product post-20714 status-publish instock product_cat-geschenk-und-probiersets has-post-thumbnail sale taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-di-caffe-biologico\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><div class=\"cg-badge-container\"><div class=\"cg-badge\"><img decoding=\"async\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/02\/bertschi-cafe-labels-logo-bio-suisse.svg\" alt=\"Caff\u00e8 biologico\" title=\"Caff\u00e8 biologico\"><\/div><div class=\"cg-badge\"><img decoding=\"async\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/02\/bertschi-cafe-labels-logo-euro-bio.svg\" alt=\"Caff\u00e8 biologico EURO\" title=\"Caff\u00e8 biologico EURO\"><\/div><\/div><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffee-set-1-bertschi-cafe-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Aumento del prezzo del caff\u00e8 Bertschi\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffee-set-1-bertschi-cafe-300x300.jpg 300w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffee-set-1-bertschi-cafe-150x150.jpg 150w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2023\/12\/kaffee-set-1-bertschi-cafe-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Set di caff\u00e8 biologico<\/h2>\n\t<span class=\"price\">A partire da <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;65.90<\/bdi><\/span><\/span>\n<\/a><div class=\"custom-group\"><span class=\"price\">Ab <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;65.90<\/bdi><\/span><\/span><div class=\"woocommerce-loop-product__buttons\"><a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-di-caffe-biologico\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_20714\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"20714\" data-product_sku=\"835bafd2c534\" aria-label=\"Seleziona le opzioni per &ldquo;Set di caff\u00e8 biologico&rdquo;\" rel=\"nofollow\">Scegli<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20714\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n<\/div><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:20714,&quot;item_id&quot;:20714,&quot;item_name&quot;:&quot;Set di caff\\u00e8 biologico&quot;,&quot;sku&quot;:&quot;835bafd2c534&quot;,&quot;price&quot;:65.900000000000005684341886080801486968994140625,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Set regalo e degustazione&quot;,&quot;id&quot;:20714,&quot;productlink&quot;:&quot;https:\\\/\\\/www.bertschi-cafe.ch\\\/it\\\/prodotto\\\/set-di-caffe-biologico\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:2,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span>\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"20714\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[20714] = {\"id\":\"20714\",\"sku\":\"835bafd2c534\",\"price\":67.6099999999999994315658113919198513031005859375,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"20714\",\"sku\":\"835bafd2c534\",\"gpf\":\"woocommerce_gpf_20714\",\"gla\":\"gla_20714\"},\"is_variable\":true,\"type\":\"variable\",\"name\":\"Set di caff\u00e8 biologico\",\"category\":[\"Set regalo e degustazione\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[20714]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t<\/li>\n<li class=\"product type-product post-20712 status-publish instock product_cat-geschenk-und-probiersets has-post-thumbnail sale taxable shipping-taxable purchasable product-type-variable has-default-attributes\">\n\t<a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-da-caffe-classico\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-3-bertschi-cafe-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Set da caff\u00e8 classico\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-3-bertschi-cafe-300x300.jpg 300w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-3-bertschi-cafe-150x150.jpg 150w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/kaffee-set-3-bertschi-cafe-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Set da caff\u00e8 classico<\/h2>\n\t<span class=\"price\">A partire da <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;44.00<\/bdi><\/span><\/span>\n<\/a><div class=\"custom-group\"><span class=\"price\">Ab <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;44.00<\/bdi><\/span><\/span><div class=\"woocommerce-loop-product__buttons\"><a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-da-caffe-classico\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_20712\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"20712\" data-product_sku=\"dfcebbaf7984\" aria-label=\"Seleziona le opzioni per &ldquo;Set da caff\u00e8 classico&rdquo;\" rel=\"nofollow\">Scegli<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_20712\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n<\/div><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:20712,&quot;item_id&quot;:20712,&quot;item_name&quot;:&quot;Set da caff\\u00e8 classico&quot;,&quot;sku&quot;:&quot;dfcebbaf7984&quot;,&quot;price&quot;:44,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Set regalo e degustazione&quot;,&quot;id&quot;:20712,&quot;productlink&quot;:&quot;https:\\\/\\\/www.bertschi-cafe.ch\\\/it\\\/prodotto\\\/set-da-caffe-classico\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:3,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span>\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"20712\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[20712] = {\"id\":\"20712\",\"sku\":\"dfcebbaf7984\",\"price\":45.1400000000000005684341886080801486968994140625,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"20712\",\"sku\":\"dfcebbaf7984\",\"gpf\":\"woocommerce_gpf_20712\",\"gla\":\"gla_20712\"},\"is_variable\":true,\"type\":\"variable\",\"name\":\"Set da caff\u00e8 classico\",\"category\":[\"Set regalo e degustazione\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[20712]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t<\/li>\n<li class=\"product type-product post-19924 status-publish last instock product_cat-geschenk-und-probiersets has-post-thumbnail sale taxable shipping-taxable purchasable product-type-variable\">\n\t<a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-di-caffe-espresso\/\" class=\"woocommerce-LoopProduct-link woocommerce-loop-product__link\"><img decoding=\"async\" width=\"300\" height=\"300\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/Kaffee-Set-4-scaled-1-300x300.jpg\" class=\"attachment-woocommerce_thumbnail size-woocommerce_thumbnail\" alt=\"Set di caff\u00e8 espresso\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/Kaffee-Set-4-scaled-1-300x300.jpg 300w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/Kaffee-Set-4-scaled-1-150x150.jpg 150w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/01\/Kaffee-Set-4-scaled-1-100x100.jpg 100w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><h2 class=\"woocommerce-loop-product__title\">Set di caff\u00e8 espresso<\/h2>\n\t<span class=\"price\">A partire da <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;59.90<\/bdi><\/span><\/span>\n<\/a><div class=\"custom-group\"><span class=\"price\">Ab <span class=\"woocommerce-Price-amount amount\"><bdi><span class=\"woocommerce-Price-currencySymbol\">&#67;&#72;&#70;<\/span>&nbsp;59.90<\/bdi><\/span><\/span><div class=\"woocommerce-loop-product__buttons\"><a href=\"https:\/\/www.bertschi-cafe.ch\/it\/prodotto\/set-di-caffe-espresso\/\" aria-describedby=\"woocommerce_loop_add_to_cart_link_describedby_19924\" data-quantity=\"1\" class=\"button product_type_variable add_to_cart_button\" data-product_id=\"19924\" data-product_sku=\"d96fd4caf8e6\" aria-label=\"Seleziona le opzioni per &ldquo;Set di caff\u00e8 espresso&rdquo;\" rel=\"nofollow\">Scegli<\/a><\/div>\t<span id=\"woocommerce_loop_add_to_cart_link_describedby_19924\" class=\"screen-reader-text\">\n\t\tQuesto prodotto ha pi\u00f9 varianti. Le opzioni possono essere scelte nella pagina del prodotto\t<\/span>\n<\/div><span class=\"gtm4wp_productdata\" style=\"display:none; visibility:hidden;\" data-gtm4wp_product_data=\"{&quot;internal_id&quot;:19924,&quot;item_id&quot;:19924,&quot;item_name&quot;:&quot;Set di caff\\u00e8 espresso&quot;,&quot;sku&quot;:&quot;d96fd4caf8e6&quot;,&quot;price&quot;:59.89999999999999857891452847979962825775146484375,&quot;stocklevel&quot;:null,&quot;stockstatus&quot;:&quot;instock&quot;,&quot;google_business_vertical&quot;:&quot;retail&quot;,&quot;item_category&quot;:&quot;Set regalo e degustazione&quot;,&quot;id&quot;:19924,&quot;productlink&quot;:&quot;https:\\\/\\\/www.bertschi-cafe.ch\\\/it\\\/prodotto\\\/set-di-caffe-espresso\\\/&quot;,&quot;item_list_name&quot;:&quot;General Product List&quot;,&quot;index&quot;:4,&quot;product_type&quot;:&quot;variable&quot;,&quot;item_brand&quot;:&quot;&quot;}\"><\/span>\t\t\t<input type=\"hidden\" class=\"pmwProductId\" data-id=\"19924\">\n\t\t\t\t\t<script>\n\t\t\t(window.pmwDataLayer = window.pmwDataLayer || {}).products                = window.pmwDataLayer.products || {};\n\t\t\twindow.pmwDataLayer.products[19924] = {\"id\":\"19924\",\"sku\":\"d96fd4caf8e6\",\"price\":61.46000000000000085265128291212022304534912109375,\"brand\":\"\",\"quantity\":1,\"dyn_r_ids\":{\"post_id\":\"19924\",\"sku\":\"d96fd4caf8e6\",\"gpf\":\"woocommerce_gpf_19924\",\"gla\":\"gla_19924\"},\"is_variable\":true,\"type\":\"variable\",\"name\":\"Set di caff\u00e8 espresso\",\"category\":[\"Set regalo e degustazione\"],\"is_variation\":false};\n\t\t\t\t\twindow.pmw_product_position = window.pmw_product_position || 1;\n\t\twindow.pmwDataLayer.products[19924]['position'] = window.pmw_product_position++;\n\t\t\t\t<\/script>\n\t\t<\/li>\n<\/ul>\n<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-14bb6a3 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"14bb6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.bertschi-cafe.ch\/shop\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<i aria-hidden=\"true\" class=\"fas fa-coffee\"><\/i>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Alle Produkte<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e6d4b2e e-flex e-con-boxed e-con e-parent\" data-id=\"e6d4b2e\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-0a26579 e-con-full e-flex e-con e-child\" data-id=\"0a26579\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b5d3f7 elementor-widget elementor-widget-heading\" data-id=\"1b5d3f7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Ihr Geschenk des guten Geschmacks<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7385d72 elementor-widget elementor-widget-text-editor\" data-id=\"7385d72\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Jedes unserer Geschenksets ist mehr als nur eine Auswahl exzellenter Kaffees \u2013 es ist eine Einladung, die Welt des Kaffees neu zu entdecken und zu genie\u00dfen. Ob als Geschenk f\u00fcr einen geliebten Menschen oder als Genuss f\u00fcr sich selbst, unsere Kaffee-Sets sind eine Bereicherung f\u00fcr jeden Anlass.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-21ed989 elementor-widget elementor-widget-n-accordion\" data-id=\"21ed989\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;expanded&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Accordion. Open links with Enter or Space, close with Escape, and navigate with Arrow Keys\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3550\" class=\"e-n-accordion-item\" open>\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"true\" aria-controls=\"e-n-accordion-item-3550\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Espresso Kaffee-Set: Dunkle R\u00f6stung, tiefer Genuss <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3550\" class=\"elementor-element elementor-element-df0a379 e-con-full e-flex e-con e-child\" data-id=\"df0a379\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-fc3cfc6 elementor-widget elementor-widget-text-editor\" data-id=\"fc3cfc6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Espresso Kaffee-Set ist die Quintessenz des italienischen Genusses, zusammengestellt f\u00fcr Liebhaber kr\u00e4ftiger und aromatischer Espressos.<\/p><p>Jedes Set enth\u00e4lt eine sorgf\u00e4ltig ausgew\u00e4hlte Kollektion von hochwertigen Espressosorten, darunter Demeter Espresso, Bio Bravo Knospe Espresso, Euro Bio Bravo Espresso, und weitere exquisite Varianten wie Sombrero Fairtrade Latino Lover und Basler Espresso. Perfektionieren Sie Ihre Espressoerfahrung mit den zwei stilvollen Espresso Tassen, die in diesem Set inkludiert sind.<\/p><p>Jede 500g-Packung Bohnen verspricht unvergleichliche Aromen und tiefgehende Geschmacksprofile, die von dunkel ger\u00f6steten Noten gepr\u00e4gt sind.<\/p><p><strong>Das Espresso Kaffee-Set enth\u00e4lt folgende Kaffees:<\/strong><\/p><ul><li>Demeter Espresso<\/li><li>Bio Bravo Knospe Espresso<\/li><li>Euro Bio Bravo Espresso<\/li><li>Sombrero Fairtrade Latino Lover<\/li><li>Basler Espresso<\/li><li>Espresso<\/li><li>2 x Espresso Tasse mit Teller<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3551\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"2\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3551\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Klassik Kaffee-Set: Von hell bis dunkel, ein vollendetes Kaffee-Erlebnis <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3551\" class=\"elementor-element elementor-element-ec6d282 e-con-full e-flex e-con e-child\" data-id=\"ec6d282\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-cb59d50 elementor-widget elementor-widget-text-editor\" data-id=\"cb59d50\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Das Klassik Kaffee-Set f\u00fchrt Sie durch ein breites Spektrum von R\u00f6stungen und Aromen, von hellem Basler Caf\u00e9 bis hin zum intensiven Espresso.<\/p><p>Auch dieses Set kommt mit zwei eleganten Caf\u00e9 Tassen, die jede Kaffeepause zu einem besonderen Moment machen. Ob Sie einen sanften Start in den Tag bevorzugen oder einen kr\u00e4ftigen Kick ben\u00f6tigen \u2013 dieses Set erf\u00fcllt alle W\u00fcnsche mit einer Vielfalt, die die Gaumenfreuden von Caf\u00e9 Cr\u00e8me bis Milchkaffee abdeckt.<\/p><p><strong>Das Klassik Kaffee-Set enth\u00e4lt folgende Kaffees:<\/strong><\/p><ul><li>Basler Caf\u00e9<\/li><li>Basler Espresso<\/li><li>Cappuccino<\/li><li>Espresso<\/li><li>Gastro-Queen<\/li><li>Gastro-King<\/li><li>2 x Caf\u00e9 Tasse mit Teller<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3552\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"3\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3552\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Fairtrade Kaffee-Set: Ethisch, exzellent, einzigartig <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3552\" class=\"elementor-element elementor-element-70adc88 e-con-full e-flex e-con e-child\" data-id=\"70adc88\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3a1ca38 elementor-widget elementor-widget-text-editor\" data-id=\"3a1ca38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Unser Fairtrade Kaffee-Set ist eine Hommage an nachhaltigen Genuss und soziale Verantwortung. Es beinhaltet Fairtrade-zertifizierte Kaffees wie Sombrero Classico in heller und mittlerer R\u00f6stung sowie den kr\u00e4ftigen Espresso Max Havelaar.<\/p><p>Dieses Set ist nicht nur eine geschmackliche Bereicherung, sondern unterst\u00fctzt auch faire Arbeitsbedingungen und nachhaltige Kaffeeproduktion. Geniessen Sie diese Spezialit\u00e4ten zusammen mit den zwei beiliegenden Caf\u00e9 Tassen, die das Trinkerlebnis abrunden.<\/p><p><strong>Das Fairtrade Kaffee-Set enth\u00e4lt folgende Kaffees:<\/strong><\/p><ul><li>Sombrero Fairtrade Classico helle R\u00f6stung<\/li><li>Sombrero Fairtrade Classico mittlere R\u00f6stung<\/li><li>Sombrero Fairtrade Espresso<\/li><li>Sombrero Latino Lover<\/li><li>Espresso Max Havelaar<\/li><li>Helvetas Classico<\/li><li>2 x Caf\u00e9 Tasse mit Teller<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-3553\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"4\" tabindex=\"-1\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-3553\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Bio Kaffee-Set: Nachhaltig genie\u00dfen <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-3553\" class=\"elementor-element elementor-element-40b6146 e-flex e-con-boxed e-con e-child\" data-id=\"40b6146\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8574e88 elementor-widget elementor-widget-text-editor\" data-id=\"8574e88\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Tauchen Sie ein in die Reinheit und das reiche Aroma unseres Bio Kaffee-Sets. Jeder Kaffee in diesem Set, von der hellen bis zur mittleren R\u00f6stung, tr\u00e4gt das Bio Knospe und das Euro Bio Siegel.<\/p><p>Diese Kaffees reflektieren unser Engagement f\u00fcr umweltschonende Praktiken und h\u00f6chste Qualit\u00e4t. Ideal f\u00fcr alle, die Wert auf \u00f6kologische Nachhaltigkeit legen, bietet dieses Set eine Palette an Geschmacksnuancen, die von sanft und nussig bis kr\u00e4ftig und vollmundig reichen.<\/p><p><strong>Das Bio Kaffee-Set enth\u00e4lt folgende Kaffees:<\/strong><\/p><ul><li>Bio Bravo Knospe Kaffee helle R\u00f6stung<\/li><li>Bio Bravo Knospe Kaffee mittlere R\u00f6stung<\/li><li>Bio Bravo Knospe Espresso<\/li><li>Euro Bio Bravo Kaffee helle R\u00f6stung<\/li><li>Euro Bio Bravo Kaffee mittlere R\u00f6stung<\/li><li>Euro Bio Bravo Espresso<\/li><li>2 x Caf\u00e9 Tasse mit Teller<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-53294bc elementor-widget elementor-widget-spacer\" data-id=\"53294bc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c694dc1 e-flex e-con-boxed e-con e-parent\" data-id=\"c694dc1\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-300ab90 elementor-widget elementor-widget-image\" data-id=\"300ab90\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"778\" height=\"788\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1.png\" class=\"attachment-large size-large wp-image-31736\" alt=\"\" srcset=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1.png 778w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1-296x300.png 296w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1-768x778.png 768w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1-600x608.png 600w, https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/11\/Geschenk-Bertschi-Cafe-1-100x100.png 100w\" sizes=\"(max-width: 778px) 100vw, 778px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-fcde862 e-flex e-con-boxed e-con e-parent\" data-id=\"fcde862\" data-element_type=\"container\" data-e-type=\"container\" id=\"Bertschi-Versprechen\" data-settings=\"{&quot;jet_parallax_layout_list&quot;:[]}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d5dcc94 elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d5dcc94\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-42df24c elementor-widget elementor-widget-heading\" data-id=\"42df24c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Das Bertschi-Versprechen<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-57e03db elementor-widget elementor-widget-text-editor\" data-id=\"57e03db\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Entdecken Sie die Welt von Bertschi Caf\u00e9 \u2013 wo Tradition auf Verantwortung trifft. Bei Bertschi Caf\u00e9 verpflichten wir uns zu den h\u00f6chsten Standards in Qualit\u00e4t und Nachhaltigkeit, um nicht nur exzellenten Kaffee zu bieten, sondern auch die Umwelt zu sch\u00fctzen und die Gemeinschaften zu unterst\u00fctzen, die unsere Bohnen anbauen. Jedes unserer sorgf\u00e4ltig zusammengestellten Geschenksets spiegelt diese Werte wider und bietet Kaffeeliebhabern eine bewusste Wahl, die sich nicht nur im Geschmack, sondern auch in der positiven Wirkung auf die Welt manifestiert.<\/p>\n<p>W\u00e4hlen Sie aus unserer vielf\u00e4ltigen Palette an Kaffeesets und erleben Sie, wie die Leidenschaft f\u00fcr erstklassigen Kaffee und das Engagement f\u00fcr faire Bedingungen sich in jedem Schluck vereinen. Unsere Geschenksets sind mehr als nur Kaffee; sie sind ein Statement f\u00fcr Qualit\u00e4t und Nachhaltigkeit \u2013 ideal f\u00fcr alle, die auf der Suche nach einem durchdachten und umweltbewussten Geschenk sind.<\/p><p>Treten Sie ein in die Welt von Bertschi Caf\u00e9 und lassen Sie sich von unseren Werten inspirieren, w\u00e4hrend Sie die aussergew\u00f6hnlichen Aromen unseres Kaffees geniessen.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d06821b elementor-widget-divider--view-line elementor-widget elementor-widget-divider\" data-id=\"d06821b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"divider.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-divider\">\n\t\t\t<span class=\"elementor-divider-separator\">\n\t\t\t\t\t\t<\/span>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d361bcd elementor-widget elementor-widget-image\" data-id=\"d361bcd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1063\" height=\"250\" src=\"https:\/\/www.bertschi-cafe.ch\/webseite\/wp-content\/uploads\/2024\/02\/bertschi-home-stimmungsbild-kaffee-gipfeli.svg\" class=\"attachment-full size-full wp-image-20149\" alt=\"Kaffee Gipfeli\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eb0e8b2 elementor-widget elementor-widget-html\" data-id=\"eb0e8b2\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"html.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<script>\r\njQuery(document).ready(function($) {\r\n    $(document).on('click', '[data-tp-sc-link]', function(e) {\r\n        e.preventDefault();\r\n        const isExternal = $(this).attr('data-tp-sc-link-external') === 'yes';\r\n        const url = $(this).attr('data-tp-sc-link');\r\n\r\n        if (isExternal) {\r\n            window.open(url, '_blank');\r\n        } else {\r\n            window.location.href = url;\r\n        }\r\n    });\r\n});\r\n<\/script>\r\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>Verschenken Sie echten Kaffeegenuss Das Bertschi-Versprechen Exklusive Kaffee-Sets f\u00fcr jeden Anlass Entdecken Sie die Welt exquisiter Kaffees mit unseren massgeschneiderten Geschenksets Alle Produkte Ihr Geschenk des guten Geschmacks Jedes unserer Geschenksets ist mehr als nur eine Auswahl exzellenter Kaffees \u2013 es ist eine Einladung, die Welt des Kaffees neu zu entdecken und zu genie\u00dfen. Ob [&hellip;]<\/p>\n","protected":false},"author":197,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_coblocks_attr":"","_coblocks_dimensions":"","_coblocks_responsive_height":"","_coblocks_accordion_ie_support":"","om_disable_all_campaigns":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"class_list":["post-31438","page","type-page","status-publish","hentry"],"acf":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/pages\/31438","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/users\/197"}],"replies":[{"embeddable":true,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/comments?post=31438"}],"version-history":[{"count":26,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/pages\/31438\/revisions"}],"predecessor-version":[{"id":31739,"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/pages\/31438\/revisions\/31739"}],"wp:attachment":[{"href":"https:\/\/www.bertschi-cafe.ch\/it\/wp-json\/wp\/v2\/media?parent=31438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}